{"id":456,"date":"2019-07-22T15:02:21","date_gmt":"2019-07-22T13:02:21","guid":{"rendered":"https:\/\/www.senfter-holding.com\/impressum\/"},"modified":"2022-06-10T08:26:53","modified_gmt":"2022-06-10T06:26:53","slug":"impressum","status":"publish","type":"page","link":"https:\/\/www.senfter-holding.com\/en\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"\r\n<p><strong>Bilder:<\/strong><br \/>Alle Bilder auf der Seite www.senfter-holding.com sind urheberrechtlich gesch\u00fctzt und d\u00fcrfen nicht weitergeleitet oder anderweitig verwendet werden.<br \/>Effekt!, \u00a9Shutterstock, Senfter Holding AG<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Bilder:Alle Bilder auf der Seite www.senfter-holding.com sind urheberrechtlich gesch\u00fctzt und d\u00fcrfen nicht weitergeleitet oder anderweitig verwendet werden.Effekt!, \u00a9Shutterstock, Senfter Holding AG<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"template-dsgvo-impressum.php","meta":[],"categories":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Impressum - www.senfter-holding.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.senfter-holding.com\/en\/impressum\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impressum - www.senfter-holding.com\" \/>\n<meta property=\"og:description\" content=\"Bilder:Alle Bilder auf der Seite www.senfter-holding.com sind urheberrechtlich gesch\u00fctzt und d\u00fcrfen nicht weitergeleitet oder anderweitig verwendet werden.Effekt!, \u00a9Shutterstock, Senfter Holding AG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.senfter-holding.com\/en\/impressum\/\" \/>\n<meta property=\"og:site_name\" content=\"www.senfter-holding.com\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-10T06:26:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.senfter-holding.com\/en\/impressum\/\",\"url\":\"https:\/\/www.senfter-holding.com\/en\/impressum\/\",\"name\":\"Impressum - www.senfter-holding.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.senfter-holding.com\/#website\"},\"datePublished\":\"2019-07-22T13:02:21+00:00\",\"dateModified\":\"2022-06-10T06:26:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.senfter-holding.com\/en\/impressum\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.senfter-holding.com\/en\/impressum\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.senfter-holding.com\/en\/impressum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.senfter-holding.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impressum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.senfter-holding.com\/#website\",\"url\":\"https:\/\/www.senfter-holding.com\/\",\"name\":\"www.senfter-holding.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.senfter-holding.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impressum - www.senfter-holding.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.senfter-holding.com\/en\/impressum\/","og_locale":"en_US","og_type":"article","og_title":"Impressum - www.senfter-holding.com","og_description":"Bilder:Alle Bilder auf der Seite www.senfter-holding.com sind urheberrechtlich gesch\u00fctzt und d\u00fcrfen nicht weitergeleitet oder anderweitig verwendet werden.Effekt!, \u00a9Shutterstock, Senfter Holding AG","og_url":"https:\/\/www.senfter-holding.com\/en\/impressum\/","og_site_name":"www.senfter-holding.com","article_modified_time":"2022-06-10T06:26:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.senfter-holding.com\/en\/impressum\/","url":"https:\/\/www.senfter-holding.com\/en\/impressum\/","name":"Impressum - www.senfter-holding.com","isPartOf":{"@id":"https:\/\/www.senfter-holding.com\/#website"},"datePublished":"2019-07-22T13:02:21+00:00","dateModified":"2022-06-10T06:26:53+00:00","breadcrumb":{"@id":"https:\/\/www.senfter-holding.com\/en\/impressum\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.senfter-holding.com\/en\/impressum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.senfter-holding.com\/en\/impressum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.senfter-holding.com\/en\/"},{"@type":"ListItem","position":2,"name":"Impressum"}]},{"@type":"WebSite","@id":"https:\/\/www.senfter-holding.com\/#website","url":"https:\/\/www.senfter-holding.com\/","name":"www.senfter-holding.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.senfter-holding.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.senfter-holding.com\/en\/wp-json\/wp\/v2\/pages\/456"}],"collection":[{"href":"https:\/\/www.senfter-holding.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.senfter-holding.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.senfter-holding.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.senfter-holding.com\/en\/wp-json\/wp\/v2\/comments?post=456"}],"version-history":[{"count":2,"href":"https:\/\/www.senfter-holding.com\/en\/wp-json\/wp\/v2\/pages\/456\/revisions"}],"predecessor-version":[{"id":799,"href":"https:\/\/www.senfter-holding.com\/en\/wp-json\/wp\/v2\/pages\/456\/revisions\/799"}],"wp:attachment":[{"href":"https:\/\/www.senfter-holding.com\/en\/wp-json\/wp\/v2\/media?parent=456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.senfter-holding.com\/en\/wp-json\/wp\/v2\/categories?post=456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}